{"id":28944,"date":"2023-10-17T09:52:11","date_gmt":"2023-10-17T07:52:11","guid":{"rendered":"https:\/\/www.convittocampanella.edu.it\/wbs\/?page_id=28944"},"modified":"2023-10-17T09:52:11","modified_gmt":"2023-10-17T07:52:11","slug":"piano-di-evacuazione-e-di-emergenza-pee-2023-24","status":"publish","type":"page","link":"https:\/\/www.convittocampanella.edu.it\/wbs\/piano-di-evacuazione-e-di-emergenza-pee-2023-24\/","title":{"rendered":"Piano di evacuazione e di emergenza (PEE) 2023\/24"},"content":{"rendered":"<p><a href=\"https:\/\/www.convittocampanella.edu.it\/wbs\/wp-content\/uploads\/2023\/10\/20231010_piano_di_evacuazione_e_di_emergenza_2023.pdf\">Piano di evacuazione e di emergenza (PEE) 2023\/24<\/a><\/p>\n<p><a href=\"https:\/\/www.convittocampanella.edu.it\/wbs\/wp-content\/uploads\/2023\/10\/20231010_PEE_Allegato_1_modulo_assegna_incarichi.pdf\">Piano di evacuazione e di emergenza &#8211; Allegato 1<\/a><\/p>\n<p><a href=\"https:\/\/www.convittocampanella.edu.it\/wbs\/wp-content\/uploads\/2023\/10\/20231010_PEE_-Allegat_-2_procedure_-di_emergenza.pdf\">Piano di evacuazione e di emergenza &#8211; Allegato 2<\/a><\/p>\n<p><a href=\"https:\/\/www.convittocampanella.edu.it\/wbs\/wp-content\/uploads\/2023\/10\/20231010_PEE_Allegato_3_scheda_informativa_genitori.pdf\">Piano di evacuazione e di emergenza &#8211; Allegato 3<\/a><\/p>\n<p><a href=\"https:\/\/www.convittocampanella.edu.it\/wbs\/wp-content\/uploads\/2023\/10\/20231010_PEE_Allegato_4_modulo_evacuazione.pdf\">Piano di evacuazione e di emergenza &#8211; Allegato 4<\/a><\/p>\n<p><a href=\"https:\/\/www.convittocampanella.edu.it\/wbs\/wp-content\/uploads\/2023\/10\/20231010_PEE_-Allegato_5_incarichi_aule_apri_chiudi_fila.pdf\">Piano di evacuazione e di emergenza &#8211; Allegato 5<\/a><\/p>\n<p><a href=\"https:\/\/www.convittocampanella.edu.it\/wbs\/wp-content\/uploads\/2023\/10\/20231010_PEE_Allegato_6_scheda_infor_per_inseg_e_alunni.pdf\">Piano di evacuazione e di emergenza &#8211; Allegato 6<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Piano di evacuazione e di emergenza (PEE) 2023\/24 Piano di evacuazione e di emergenza &#8211; Allegato 1 Piano di evacuazione e di emergenza &#8211; Allegato 2 Piano di evacuazione e di emergenza &#8211; Allegato 3 Piano di evacuazione e di emergenza &#8211; Allegato 4 Piano di evacuazione e di emergenza &#8211; Allegato 5 Piano di &hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-28944","page","type-page","status-publish","hentry"],"featured_image_src":null,"_links":{"self":[{"href":"https:\/\/www.convittocampanella.edu.it\/wbs\/wp-json\/wp\/v2\/pages\/28944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.convittocampanella.edu.it\/wbs\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.convittocampanella.edu.it\/wbs\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.convittocampanella.edu.it\/wbs\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.convittocampanella.edu.it\/wbs\/wp-json\/wp\/v2\/comments?post=28944"}],"version-history":[{"count":0,"href":"https:\/\/www.convittocampanella.edu.it\/wbs\/wp-json\/wp\/v2\/pages\/28944\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.convittocampanella.edu.it\/wbs\/wp-json\/wp\/v2\/media?parent=28944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}